{"id":2828,"date":"2025-03-27T15:13:26","date_gmt":"2025-03-27T15:13:26","guid":{"rendered":"https:\/\/lookalocker.com\/?page_id=2828"},"modified":"2025-03-28T09:42:38","modified_gmt":"2025-03-28T09:42:38","slug":"terminos-condiciones","status":"publish","type":"page","link":"https:\/\/lookalocker.com\/de\/terminos-condiciones\/","title":{"rendered":"AUFTRAGSBESTIMMUNGEN UND -BEDINGUNGEN"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2828\" class=\"elementor elementor-2828\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0169414 e-flex e-con-boxed e-con e-parent\" data-id=\"0169414\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-999ccae elementor-widget elementor-widget-text-editor\" data-id=\"999ccae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<main class=\"widget-content aviso-legal\"><br \/><!-- INICIO: Ajustes generales del contenedor del widget de aviso legal --><br \/><!-- Aqu\u00ed puedes a\u00f1adir estilos generales como padding, margin, background-color, etc. --><br \/><!-- Tambi\u00e9n puedes ajustar esto directamente en las opciones de estilo del widget en Gutenberg. --><\/main><p><style>\n        \/* Estilos generales del aviso legal - Hereda estilos de pol\u00edtica de privacidad y ajusta si es necesario *\/<br \/>        \/* Puedes modificar estos estilos para personalizar la apariencia dentro de Gutenberg *\/<br \/>        .widget-content.aviso-legal {<br \/>            background-color: #FEF1E400; \/* Color de fondo general (transparente ahora - #FEF1E4 para color) *\/<br \/>            color: #222222; \/* Color de texto principal *\/<br \/>            font-family: Poppins, sans-serif; \/* Tipograf\u00eda *\/<br \/>            line-height: 1.6; \/* Espaciado entre l\u00edneas *\/<br \/>            padding: 20px; \/* Espaciado interno *\/<br \/>            border-radius: 8px; \/* Bordes redondeados si se desea *\/<br \/>            width: 100%; \/* Asegura que el widget ocupe el ancho completo *\/<br \/>            display: flex; \/* Para centrar el contenido interno si es necesario *\/<br \/>            justify-content: center; \/* Para centrar el contenido interno horizontalmente *\/<br \/>        }<\/p>\n<p>        .aviso-legal-container { \/* Nuevo contenedor interno para aviso legal *\/<br \/>            background: white; \/* Fondo blanco para la caja de texto *\/<br \/>            padding: 20px;<br \/>            border-radius: 8px;<br \/>            box-shadow: 0 0 10px rgba(0, 0, 0, 0.1); \/* Sombra para la caja blanca *\/<br \/>            max-width: 800px; \/* Ancho m\u00e1ximo del contenido interno (ajusta si quieres m\u00e1s ancho) *\/<br \/>            width: 100%; \/* Asegura que el contenedor interno ocupe el ancho disponible dentro del widget *\/<br \/>        }<\/p>\n<p>        .aviso-legal-titulo {<br \/>            color: #222222; \/* Color del t\u00edtulo principal *\/<br \/>            font-size: 2.5em; \/* Aumentamos el tama\u00f1o del t\u00edtulo principal *\/<br \/>            font-weight: bold; \/* Hacemos el t\u00edtulo principal m\u00e1s bold *\/<br \/>            margin-bottom: 20px; \/* A\u00f1adimos margen inferior para separarlo del contenido *\/<br \/>            \/* Ajustes adicionales para el t\u00edtulo principal (tama\u00f1o, margen, etc.) *\/<br \/>        }<\/p>\n<p>        .aviso-legal-section-titulo {<br \/>            color: #222222; \/* Color de los t\u00edtulos de secci\u00f3n *\/<br \/>            font-size: 1.8em; \/* Tama\u00f1o ligeramente menor para los t\u00edtulos de secci\u00f3n *\/<br \/>            font-weight: bold; \/* Mantenemos los t\u00edtulos de secci\u00f3n en bold tambi\u00e9n, o puedes cambiar a 'normal' si prefieres *\/<br \/>            margin-top: 25px; \/* A\u00f1adimos margen superior para separar secciones *\/<br \/>            margin-bottom: 10px; \/* A\u00f1adimos margen inferior para separar del texto de la secci\u00f3n *\/<br \/>            \/* Ajustes adicionales para los t\u00edtulos de secci\u00f3n *\/<br \/>        }<\/p>\n<p>        .aviso-legal-section-texto {<br \/>            \/* Ajustes para el texto de las secciones *\/<br \/>            font-size: 1em; \/* Tama\u00f1o base para el texto de la secci\u00f3n, puedes ajustarlo *\/<br \/>        }<\/p>\n<p>        .aviso-legal-section-texto strong {<br \/>            color: #FF6210; \/* Color para el texto en negrita\/strong *\/<br \/>        }<\/p>\n<p>        .aviso-legal-section-texto ul {<br \/>            padding-left: 20px; \/* Espaciado para listas *\/<br \/>        }<\/p>\n<p>        .aviso-legal-list-item {<br \/>            \/* Estilos para los items de lista si se necesitan *\/<br \/>        }<\/p>\n<p>        \/* **ESTILOS PARA LOS ENLACES** *\/<br \/>        .aviso-legal-container a,<br \/>        .politica-privacidad-container a { \/* Aplicamos estilos a los links en ambos contenedores *\/<br \/>            color: #007BFF; \/* Color azul est\u00e1ndar para enlaces - visible en blanco *\/<br \/>            text-decoration: none; \/* Quitamos la decoraci\u00f3n de subrayado por defecto *\/<br \/>        }<\/p>\n<p>        .aviso-legal-container a:hover,<br \/>        .politica-privacidad-container a:hover { \/* Estilo al pasar el rat\u00f3n por encima *\/<br \/>            color: #0056b3; \/* Un azul m\u00e1s oscuro para el hover *\/<br \/>            text-decoration: underline; \/* Volvemos a poner el subrayado en hover para feedback visual *\/<br \/>        }<\/p>\n<p>        .aviso-legal-container a:visited,<br \/>        .politica-privacidad-container a:visited { \/* Estilo para enlaces visitados (opcional) *\/<br \/>            color: #868e96; \/* Un gris m\u00e1s suave para enlaces visitados - opcional *\/<br \/>        }<br \/>        \/* **FIN DE ESTILOS PARA LOS ENLACES** *\/<\/p>\n<p>        \/* FIN: Estilos generales del aviso legal *\/<br \/>    <\/style><\/p><p><!-- FIN: Ajustes generales del contenedor del widget de aviso legal --><\/p><div class=\"aviso-legal-container\"><h1 class=\"widget-title aviso-legal-titulo\" style=\"text-align: center;\"><b>CONDICIONES DE CONTRATACI\u00d3N<\/b><\/h1><section class=\"aviso-legal-section\"><h2 class=\"aviso-legal-section-titulo\"><b>IDENTIFICACI\u00d3N <\/b><\/h2><div class=\"aviso-legal-section-texto\"><p>Las presentes condiciones de contrataci\u00f3n regulan el acceso y uso del Sitio Web www.lookalocker.com (en adelante \u201c<b><i>Plataforma<\/i><\/b>\u201d), titularidad de SONIA COREAS MARIN, con domicilio en C\/Bronce 25, 28045,\u00a0 Madrid, Espa\u00f1a, con DNI 03914737E, (en adelante el \u201cTITULAR\u201d).<\/p><p>El Cliente puede ponerse en contacto SONIA COREAS MARIN a trav\u00e9s de la siguiente direcci\u00f3n de correo electr\u00f3nico: info@lookalocker.com.\u00a0<\/p><p>El registro en la Plataforma y\/o el uso de la misma implica que el Cliente ha le\u00eddo, entendido y aceptado, sin reserva alguna, las presentes Condiciones de Contrataci\u00f3n.<\/p><p>El acceso y navegaci\u00f3n por el Sitio Web no requerir\u00e1 el registro de los Clientes y ser\u00e1 totalmente gratuito.<\/p><\/div><\/section><section class=\"aviso-legal-section\"><h2 class=\"aviso-legal-section-titulo\"><b>SERVICIOS<\/b><\/h2><div class=\"aviso-legal-section-texto\"><p>A trav\u00e9s de la Plataforma se ofrece a los Clientes la posibilidad de contratar servicios que consisten en la reserva por un tiempo determinado (por d\u00edas) de un locker o taquilla, con las dimensiones escogidas (a elegir entre taquillas medianas (M), cuyas medidas son de 580mmX436mmX293mm; taquillas grandes (L), cuyas medidas son de 580mmX436mmX560mm; taquillas extragrandes (XL), cuyas medidas son de 580mmX436mmX856mm, abierto las 24 horas en la ciudad de Madrid, (en adelante \u201c<b><i>Servicios<\/i><\/b>\u201d).<\/p><p>Para la correcta prestaci\u00f3n de los servicios descritos, no ser\u00e1 necesario crearse cuenta de Cliente.<\/p><\/div><\/section><section class=\"aviso-legal-section\"><h2 class=\"aviso-legal-section-titulo\"><b>CONDUCTA DE LOS CLIENTES<\/b><\/h2><div class=\"aviso-legal-section-texto\"><ul><li aria-level=\"1\"><b>En la Plataforma<\/b><\/li><\/ul><p>Los\u00a0Clientes se comprometen a hacer un uso l\u00edcito, diligente, honesto y correcto de cuanta informaci\u00f3n o contenidos tengan acceso a trav\u00e9s de la Plataforma, y todo ello bajo los principios de la buena fe y respetando en todo momento a la legalidad vigente y a las presentes condiciones de contrataci\u00f3n.<\/p><p>En particular, pero sin limitaci\u00f3n, los\u00a0Clientes no deber\u00e1n usar la Plataforma con fines fraudulentos, o relacionados con delitos penales o actividades il\u00edcitas de ning\u00fan tipo.\u00a0\u00a0<\/p><p>TITULAR se reserva el derecho a denegar cualquier intento de acceso a la Plataforma eliminar o modificar contenidos, o cancelar la prestaci\u00f3n de Servicios en los casos en los que se produzca una utilizaci\u00f3n incorrecta de la Plataforma.<\/p><ul><li aria-level=\"1\"><b>Uso del Servicio contratado<\/b><\/li><\/ul><p>El Cliente, se compromete a utilizar el Servicio contratado de la siguiente manera:<\/p><ul><li aria-level=\"1\"><b>Uso exclusivo para almacenamiento personal:<\/b> Depositar \u00fanicamente bienes de su propiedad que necesite guardar temporalmente en un lugar seguro.<\/li><li aria-level=\"1\"><b>Uso diligente y correcto cierre<\/b>: Asegurarse de que el locker quede correctamente cerrado al abandonar el local, ya sea despu\u00e9s de insertar o retirar sus pertenencias. Recuerde que el TITULAR no se hace responsable de extrav\u00edos, robos o posibles desperfectos.<\/li><\/ul><ul><li aria-level=\"1\"><b>Prohibici\u00f3n de usos ilegales:<\/b> No utilizar las consignas para fines il\u00edcitos o no autorizados, incluyendo el almacenamiento de bienes cuya tenencia o tr\u00e1fico sea ilegal (objetos robados, drogas, materiales pornogr\u00e1ficos o denigrantes, etc.).<\/li><li aria-level=\"1\"><b>Restricciones de objetos con licencia:<\/b> No depositar bienes cuya tenencia requiera una licencia espec\u00edfica sin contar con dicha autorizaci\u00f3n (por ejemplo, armas).<\/li><li aria-level=\"1\"><b>Prohibici\u00f3n de materiales peligrosos:<\/b> No introducir sustancias contaminantes, inflamables o cualquier otro material que represente un riesgo para la seguridad.<\/li><li aria-level=\"1\"><b>Restricciones sobre alimentos:<\/b> No introducir comida, salvo que se trate de productos envasados que no puedan derramarse, manchar los lockers ni generar olores.<\/li><li aria-level=\"1\"><b>Protecci\u00f3n del c\u00f3digo de acceso:<\/b> No compartir la clave de seguridad con terceros, siendo el Usuario plenamente responsable de su uso indebido. El c\u00f3digo de reserva es personal e intransferible, por lo que solo el titular de la reserva puede utilizarlo para retirar sus pertenencias.<\/li><\/ul><ul><li aria-level=\"1\"><b>Prohibici\u00f3n de tr\u00e1fico de bienes:<\/b> No utilizar las consignas para el intercambio de objetos entre terceros. Queda prohibido su uso como medio de distribuci\u00f3n de bienes.<\/li><li aria-level=\"1\"><b>Acceso limitado al local<\/b>: Permanecer en el local \u00fanicamente el tiempo necesario para acceder a la consigna alquilada y gestionar los objetos depositados.<\/li><li aria-level=\"1\"><b>Prohibici\u00f3n de consumo dentro del local:<\/b> No ingerir alimentos ni bebidas en el interior del establecimiento.<\/li><li aria-level=\"1\"><b>Mantenimiento del estado de la consigna: <\/b>Dejar la consigna en el mismo estado en que se encontr\u00f3 al finalizar el servicio y notificar cualquier incidencia a info@lookalocker.com.\u00a0<\/li><li aria-level=\"1\"><b>Restricciones sobre fotos y v\u00eddeos:<\/b> No realizar fotograf\u00edas ni grabaciones dentro del local, salvo las necesarias para captar el n\u00famero de reserva o seguridad.<\/li><li aria-level=\"1\"><b>Pago con tarjeta de su titularidad:<\/b> Abonar el precio del servicio con una tarjeta de cr\u00e9dito\/d\u00e9bito de su titularidad o con la debida autorizaci\u00f3n de su propietario.<\/li><\/ul><\/div><\/section><section class=\"aviso-legal-section\"><h2 class=\"aviso-legal-section-titulo\"><b>PRECIO Y FORMA DE PAGO<\/b><\/h2><p><strong>a) Precio<\/strong><\/p><p>Todos los precios de los servicios que se indican a trav\u00e9s del Sitio Web se expresan en <b>Euros (\u20ac)<\/b> e incluyen el IVA de 21% y los dem\u00e1s impuestos que pudieran corresponder. El precio facturado es el indicado en la confirmaci\u00f3n del pedido que ser\u00e1 enviada.<\/p><\/section><p><strong>b)<\/strong> <b>Medios de pago<\/b><\/p><section class=\"aviso-legal-section\"><div class=\"aviso-legal-section-texto\"><p>El Cliente podr\u00e1 pagar el importe correspondiente a su pedido mediante los medios de pago aceptados en el Sitio Web:\u00a0<\/p><\/div><ul><li class=\"aviso-legal-section-texto\"><b>Pago con tarjeta<\/b> (Visa, MasterCard). Si su medio de pago es la tarjeta bancaria, al hacer click en \u00abComprar y proceder al pago\u00bb usted est\u00e1 confirmando que la tarjeta de cr\u00e9dito es suya. Si recibe una notificaci\u00f3n de que se ha rechazado tu tarjeta y has verificado que la tarjeta no ha expirado y que el n\u00famero de informaci\u00f3n asociados a tu tarjeta no contiene ning\u00fan error, deber\u00e1s contactar con tu banco en primer lugar para averiguar cu\u00e1l es el motivo del rechazo o falta de autorizaci\u00f3n.<\/li><li><strong>Google y Apple Pay<\/strong><\/li><\/ul><p>Se enviar\u00e1 un correo electr\u00f3nico al Cliente, confirmando los detalles del servicio. Dicho correo electr\u00f3nico asignar\u00e1 un c\u00f3digo personalizado con el c\u00f3digo de acceso al local y a la taquilla asignada, y detallar\u00e1 las caracter\u00edsticas del Servicio, su precio y los datos de la opci\u00f3n elegida para efectuar el pago del Servicio contratado, as\u00ed como la factura simple una vez se haya formalizado el pedido, es decir, tras la aceptaci\u00f3n de las presentes Condiciones de Contrataci\u00f3n y el pago que corresponda.<\/p><p>Se garantiza a los Clientes que el proceso de pago se realiza con absoluta seguridad, de acuerdo con los protocolos y servicios de seguridad exigidos.<\/p><p>El Cliente debe notificarnos cualquier cargo indebido o fraudulento en la tarjeta utilizada para las compras, a trav\u00e9s del env\u00edo de un email info@lookalocker.com, en el menor plazo de tiempo posible para que TITULAR pueda realizar las gestiones oportunas.<\/p><p><strong>c) Cupones de descuento<\/strong><\/p><p>Los cupones de descuento son ofertas promocionales que permiten una rebaja parcial o total del precio del pedido o producto. Los cupones son de un solo uso por persona.<\/p><p>Los cupones de descuento pueden tener algunas restricciones o limitaciones adicionales (por ejemplo, una cantidad limitada de cupones, o un periodo determinado de canjeo). En estos casos, podr\u00e1 consultar dichas condiciones adicionales en el texto que acompa\u00f1a al cup\u00f3n.\u00a0 As\u00ed pues, las condiciones de cada campa\u00f1a ser\u00e1n proporcionadas al facilitar el cup\u00f3n de descuento. Si el cup\u00f3n de descuento ya no tiene validez en el momento de realizar la contrataci\u00f3n del servicio, se informar\u00e1 antes de que se efect\u00fae el pago.<\/p><p>Para poder disfrutar del descuento, debe introducir el c\u00f3digo en la pantalla de Pago y selecciona\u00a0<b>Aplicar\u00a0<\/b>antes de abonar el importe restante por el pedido.\u00a0<\/p><p>Adem\u00e1s, debe tener en cuenta lo siguiente:<\/p><ul><li aria-level=\"1\">Los cupones de descuentos no son acumulables con otras promociones.<\/li><li aria-level=\"1\">Se puede utilizar solamente un cup\u00f3n de descuento por carrito de la compra.<\/li><li aria-level=\"1\">Los cupones no son reembolsables, deben utilizarse en una solo pago, de uno o m\u00e1s lockers contratados a trav\u00e9s de este sitio web y no pueden ser canjeados por dinero en efectivo.\u00a0<\/li><li aria-level=\"1\">Los cupones de descuento pueden ser utilizados para el pago a partir de un cierto importe m\u00ednimo de compra teniendo en cuenta el precio final de venta (IVA incluido).<\/li><li aria-level=\"1\">En caso de que el importe del cup\u00f3n de descuento no cubra el precio final (IVA incluido), deber\u00e1 pagar la diferencia, lo cual \u00fanicamente ser\u00e1 posible utilizando los medios de pago indicados anteriormente.<\/li><li aria-level=\"1\">En caso de que el cup\u00f3n tenga un valor mayor al total del precio del servicio contratado, la diferencia no ser\u00e1 reembolsable, ni tampoco podr\u00e1 acumularse para uso posterior, perdiendo entonces la diferencia.<\/li><li aria-level=\"1\">Los cupones de descuento caducar\u00e1n si no se han utilizado transcurrido el periodo de vigencia del cup\u00f3n.\u00a0<\/li><li aria-level=\"1\">Si el cup\u00f3n fue utilizado anteriormente, se mostrar\u00e1 un mensaje de error.<\/li><\/ul><h2><b>INFORMACI\u00d3N SOBRE LOS SERVICIOS<\/b><\/h2><p>Los datos incluidos en el Sitio Web en las descripciones de los diferentes lockers que se ponen a la disposici\u00f3n del Cliente en la contrataci\u00f3n de los Servicios tienen una funci\u00f3n meramente informativa.\u00a0<\/p><p>Por tanto, TITULAR declina cualquier responsabilidad por la aparici\u00f3n de errores en dicha informaci\u00f3n, si bien se compromete a tomar todas las medidas a su alcance para corregir en la mayor brevedad posible los referidos errores u omisiones tras haber sido informada de los mismos.<\/p><p>El servicio contratado finaliza en el momento en que se abre la consiga para retirar los bultos de manera definitiva. En caso de olvido de alg\u00fan bulto, el TITULAR, no se hace responsable en ning\u00fan caso.<\/p><h2><b>PLAZOS Y PENALIZACI\u00d3N POR RETRASO<\/b><\/h2><p>Una vez el Servicio contratado, puede utilizar el locker tantas veces como lo desee a lo largo del periodo reservado en la contrataci\u00f3n del Servicio.<\/p><p>No obstante, si excede el tiempo contratado inicialmente, en la pantalla central de los lockers, se le pedir\u00e1 que abone la penalizaci\u00f3n por d\u00eda superado, seg\u00fan la tarifa de la taquilla elegida.<\/p><\/section><section class=\"aviso-legal-section\"><h2 class=\"aviso-legal-section-titulo\">DERECHO DE SESITIMIENTO Y RECLAMACIONES<\/h2><div class=\"aviso-legal-section-texto\"><p>Una vez que el Cliente haya realizado el pago del Servicio y este haya comenzado a prestarse, no ser\u00e1 aplicable el derecho de desistimiento, de acuerdo con la excepci\u00f3n contemplada en el art\u00edculo 103 a) de la Ley General para la Defensa de Consumidores y Usuarios. En consecuencia, una vez iniciada la prestaci\u00f3n del Servicio, no se podr\u00e1 reembolsar el importe abonado.<\/p><p>En caso de querer formalizar una reclamaci\u00f3n, podr\u00e1 hacerlo dirigi\u00e9ndose al TITULAR al correo electr\u00f3nico info@lookalocker.com.<\/p><\/div><\/section><section class=\"aviso-legal-section\"><h2 class=\"aviso-legal-section-titulo\">EXCLUSI\u00d3N DE RESPONSABILIDAD<\/h2><\/section><section class=\"aviso-legal-section\"><div class=\"aviso-legal-section-texto\"><p>El Cliente se compromete a utilizar la Plataforma de conformidad con la normativa vigente y con las presentes Condiciones de Contrataci\u00f3n. Asimismo, el Cliente asume exclusivamente la responsabilidad de haber proporcionado informaci\u00f3n en contra de la legalidad vigente, as\u00ed como todos los perjuicios y consecuencias derivadas, eximiendo de cualquier responsabilidad a TITULAR.<\/p><p>TITULAR no otorga ninguna garant\u00eda ni se hace responsable, en ning\u00fan caso, de los da\u00f1os y perjuicios de cualquier naturaleza que pudieran derivarse del acceso o uso de los contenidos de la Plataforma. Entre otras, y a t\u00edtulo enunciativo y no limitativo,\u00a0TITULAR no se responsabiliza de las siguientes circunstancias:\u00a0<\/p><ul><li aria-level=\"1\">De la falta de disponibilidad, mantenimiento y efectivo funcionamiento de la Plataforma y de sus servicios o contenidos, excluy\u00e9ndose, en la m\u00e1xima medida\u00a0permitida por la legislaci\u00f3n vigente, cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que puedan deberse a la falta de disponibilidad o de continuidad del funcionamiento de la Plataforma.<\/li><li aria-level=\"1\">De la falta de utilidad de la Plataforma o los contenidos para cualquier servicio.\u00a0\u00a0<\/li><li aria-level=\"1\">Del contenido de otras p\u00e1ginas de Internet a las que puedan dirigirse links o enlaces colocados en la Plataforma.<\/li><li aria-level=\"1\">De la existencia de virus, programas maliciosos o lesivos en la Plataforma.<\/li><li aria-level=\"1\">Del uso il\u00edcito, negligente, fraudulento, contrario a las presentes Condiciones de Contrataci\u00f3n\u00a0o a la buena fe, de la Plataforma o sus contenidos, por parte de los\u00a0Clientes, incluido cualquier infracci\u00f3n de los derechos de\u00a0Propiedad Intelectual\u00a0y\/o Industrial de TITULAR o de terceros.\u00a0<\/li><li aria-level=\"1\">De las incidencias ocasionadas por la falta de la diligencia debida por parte del\u00a0Cliente o por el uso indebido de la Plataforma.<\/li><li aria-level=\"1\">De la publicaci\u00f3n a trav\u00e9s de la Plataforma de informaci\u00f3n, comentarios y opiniones\u00a0que infrinjan las normas mencionadas en las presentes Condiciones de Contrataci\u00f3n, la legislaci\u00f3n aplicable o los derechos de terceras partes.\u00a0<\/li><li aria-level=\"1\">De los casos de fuerza mayor, entendidos tales como el fallo, suspensi\u00f3n o interrupci\u00f3n de los servicios o utilizaci\u00f3n de la Plataforma como consecuencia de las restricciones de energ\u00eda, el bloqueo de las telecomunicaciones o de la red de Internet, acciones u omisiones de terceras personas, operadores de telecomunicaci\u00f3n o compa\u00f1\u00edas de servicios, suministro o transportes o cualesquiera otras causas o circunstancias independientes de la voluntad de\u00a0TITULAR que impidan la utilizaci\u00f3n normal de la Plataforma.<\/li><\/ul><h2><b>PROPIEDAD INTELECTUAL E INDUSTRIAL<\/b><\/h2><\/div><p>Todos los derechos sobre el contenido, dise\u00f1o y c\u00f3digo fuente de la Plataforma y, en especial, con car\u00e1cter enunciativo, pero no limitativo, todos los derechos sobre las fotograf\u00edas, im\u00e1genes, textos, logotipos, dise\u00f1os, marcas, nombres comerciales, datos que se incluyen en la Plataforma y cualesquiera otros derechos de propiedad intelectual e industrial son titularidad de TITULAR, o bien de terceros que hayan autorizado expresamente a TITULAR para la utilizaci\u00f3n de los mismos en su Plataforma.<\/p><p>Por ello y en virtud de lo dispuesto en Real Decreto Legislativo 1\/1996, de 12 de abril, por el que se aprueba el texto refundido de la Ley de Propiedad Intelectual, regularizando, aclarando y armonizando las disposiciones legales vigentes sobre la materia , as\u00ed como en la Ley 17\/2001, de 7 de diciembre de Marcas y la legislaci\u00f3n complementaria en materia de propiedad intelectual e industrial, queda expresamente prohibida la reproducci\u00f3n, transmisi\u00f3n, adaptaci\u00f3n, traducci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta Plataforma, en cualquier soporte y por cualquier medio t\u00e9cnico, salvo autorizaci\u00f3n expresa otorgada por escrito por parte de TITULAR.<\/p><p>TITULAR no concede ninguna licencia o autorizaci\u00f3n de uso de ninguna clase sobre sus derechos de propiedad intelectual e industrial o sobre cualquier otra propiedad o derecho relacionado con la Plataforma, y que en ning\u00fan caso se entender\u00e1 que el acceso de navegaci\u00f3n de los Clientes implica una renuncia, transmisi\u00f3n, licencia o cesi\u00f3n total ni parcial de dichos derechos por parte de TITULAR.\u00a0<\/p><p>Cualquier uso de esos contenidos no autorizado previamente por parte de TITULAR ser\u00e1 considerado un incumplimiento grave de los derechos de propiedad intelectual o industrial y dar\u00e1 lugar a las responsabilidades legalmente establecidas.<\/p><h2><b>PROTECCI\u00d3N DE DATOS PERSONALES<\/b><\/h2><\/section><p>Los datos de los Clientes que se recaban a trav\u00e9s de la Plataforma son recabados con la finalidad de poder prestarles los Servicios contratados a trav\u00e9s de la Plataforma.<\/p><p>Sus datos ser\u00e1n tratados en base a la necesidad de llevar a cabo la relaci\u00f3n contractual y conserv\u00e1ndose durante el tiempo necesario para la realizaci\u00f3n de la misma as\u00ed como para responder a posibles responsabilidades derivados de la misma.\u00a0<\/p><p>Tiene derecho a ejercitar su derecho de acceso, rectificaci\u00f3n, supresi\u00f3n, oposici\u00f3n, portabilidad, limitaci\u00f3n, y a no ser objeto de decisiones automatizas al siguiente correo: privacidad@lookalocker.com indicando el motivo de su petici\u00f3n, acreditando su identidad e identific\u00e1ndose como Cliente. Por \u00faltimo, si siente vulnerados sus derechos, puede presentar una reclamaci\u00f3n a la autoridad competente (www.aepd.es).\u00a0<\/p><p>El TITULAR respeta su privacidad de acuerdo con la normativa en protecci\u00f3n de datos y cumple con las medidas de seguridad necesarias. Para m\u00e1s informaci\u00f3n pue<span style=\"color: #333333;\">de consultar nuestra <a style=\"color: #333333;\" href=\"https:\/\/lookalocker.com\/de\/politica-de-privacidad\/\" target=\"_blank\" rel=\"nofollow noopener\">Datenschutzbestimmungen<\/a>.<\/span><\/p><h2><b>ENLACES<\/b><\/h2><\/div><p>La Plataforma podr\u00eda contener links o hiperv\u00ednculos a p\u00e1ginas web o aplicaciones titularidad de terceros. TITULAR no asume ninguna responsabilidad por el contenido, informaciones o servicios que pudieran aparecer en dichos sitios, y que en ning\u00fan caso implican relaci\u00f3n, aceptaci\u00f3n o respaldo alguno entre TITULAR y las personas o entidades titulares de tales contenidos o titulares de los sitios web.<\/p><h2><b>MODIFICACIONES<\/b><\/h2><p>TITULAR se reserva el derecho a realizar tantas modificaciones como considere oportunas en las presentes Condiciones de Contrataci\u00f3n, en cuyo caso se les comunicar\u00e1 previamente a los Clientes.<\/p><p>Estas modificaciones ser\u00e1n v\u00e1lidas desde su publicaci\u00f3n en la Plataforma.<\/p><h2><b>CL\u00c1USULA DE SALVAGUARDA<\/b><\/h2><p>Todas las cl\u00e1usulas o extremos de estas Condiciones de contrataci\u00f3n deben ser interpretadas de forma independiente y aut\u00f3noma, no vi\u00e9ndose afectadas el resto de las estipulaciones en caso de que una de ellas haya sido declarada nula por sentencia judicial o resoluci\u00f3n arbitral firme. Se sustituir\u00e1 la cl\u00e1usula o cl\u00e1usulas afectadas por otra u otras que preserven los efectos perseguidos por las Condiciones de contrataci\u00f3n.<\/p><h2><b>RESOLUCI\u00d3N DE CONTROVERSIAS<\/b><\/h2><p>Los presentes T\u00e9rminos y Condiciones est\u00e1n sometidos a la legislaci\u00f3n espa\u00f1ola. Las partes, de conformidad al Real Decreto Legislativo 1\/2007, de 16 de noviembre, por el que se aprueba el texto refundido de la Ley General para la Defensa de los Consumidores y Usuarios y otras leyes complementarias, se someten a los Juzgados y Tribunales del lugar de residencia de la parte que contrata el servicio.<\/p><p><!-- Cierre del contenedor interno aviso-legal-container --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CONDICIONES DE CONTRATACI\u00d3N IDENTIFICACI\u00d3N Las presentes condiciones de contrataci\u00f3n regulan el acceso y uso del Sitio Web www.lookalocker.com (en adelante \u201cPlataforma\u201d), titularidad de SONIA COREAS MARIN, con domicilio en C\/Bronce 25, 28045,\u00a0 Madrid, Espa\u00f1a, con DNI 03914737E, (en adelante el \u201cTITULAR\u201d). El Cliente puede ponerse en contacto SONIA COREAS MARIN a trav\u00e9s de la siguiente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_mbp_gutenberg_autopost":false,"footnotes":""},"class_list":["post-2828","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lookalocker.com\/de\/wp-json\/wp\/v2\/pages\/2828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lookalocker.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lookalocker.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lookalocker.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lookalocker.com\/de\/wp-json\/wp\/v2\/comments?post=2828"}],"version-history":[{"count":0,"href":"https:\/\/lookalocker.com\/de\/wp-json\/wp\/v2\/pages\/2828\/revisions"}],"wp:attachment":[{"href":"https:\/\/lookalocker.com\/de\/wp-json\/wp\/v2\/media?parent=2828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}